{"id":2426,"date":"2024-03-21T17:16:47","date_gmt":"2024-03-21T16:16:47","guid":{"rendered":"https:\/\/www.ggs-walheim.de\/?p=2426"},"modified":"2024-03-21T17:28:23","modified_gmt":"2024-03-21T16:28:23","slug":"schuelerparlament","status":"publish","type":"post","link":"https:\/\/www.ggs-walheim.de\/index.php\/2024\/03\/21\/schuelerparlament\/","title":{"rendered":"Sch\u00fclerparlament"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1440\" height=\"1080\" src=\"https:\/\/www.ggs-walheim.de\/wp-content\/uploads\/2024\/03\/Schuelerparlament-1440x1080.jpg\" alt=\"\" class=\"wp-image-2427\" style=\"width:839px;height:auto\" srcset=\"https:\/\/www.ggs-walheim.de\/wp-content\/uploads\/2024\/03\/Schuelerparlament-1440x1080.jpg 1440w, https:\/\/www.ggs-walheim.de\/wp-content\/uploads\/2024\/03\/Schuelerparlament-300x225.jpg 300w, https:\/\/www.ggs-walheim.de\/wp-content\/uploads\/2024\/03\/Schuelerparlament-1536x1152.jpg 1536w, https:\/\/www.ggs-walheim.de\/wp-content\/uploads\/2024\/03\/Schuelerparlament-800x600.jpg 800w, https:\/\/www.ggs-walheim.de\/wp-content\/uploads\/2024\/03\/Schuelerparlament.jpg 2048w\" sizes=\"auto, (max-width: 1440px) 100vw, 1440px\" \/><\/figure>\n\n\n\n<p>Das Kinderparlament der Grundschule Walheim hat gearbeitet und getagt. Wichtige Schulregeln wurden besprochen und neu verabredet.<\/p>\n\n\n\n<p>Davon berichten die Klassensprecherinnen und Klassensprecher im Rahmen eines Schulforums.<\/p>\n\n\n\n<p>Die wichtigste Regel ist hervorzuheben: WIR SIND ALLE FREUNDLICH ZUEINANDER.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Kinderparlament der Grundschule Walheim hat gearbeitet und getagt. Wichtige Schulregeln wurden besprochen und neu verabredet. Davon berichten die Klassensprecherinnen und Klassensprecher im Rahmen eines&hellip;<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":"","footnotes":""},"categories":[312],"tags":[309,311,313],"class_list":["post-2426","post","type-post","status-publish","format-standard","hentry","category-schuelerparlament","tag-kinder","tag-regeln","tag-schueler"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sch\u00fclerparlament - GGS Walheim<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ggs-walheim.de\/index.php\/2024\/03\/21\/schuelerparlament\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sch\u00fclerparlament - GGS Walheim\" \/>\n<meta property=\"og:description\" content=\"Das Kinderparlament der Grundschule Walheim hat gearbeitet und getagt. Wichtige Schulregeln wurden besprochen und neu verabredet. Davon berichten die Klassensprecherinnen und Klassensprecher im Rahmen eines&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ggs-walheim.de\/index.php\/2024\/03\/21\/schuelerparlament\/\" \/>\n<meta property=\"og:site_name\" content=\"GGS Walheim\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-21T16:16:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-21T16:28:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ggs-walheim.de\/wp-content\/uploads\/2024\/03\/Schuelerparlament-1440x1080.jpg\" \/>\n<meta name=\"author\" content=\"Tanja Braun\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tanja Braun\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ggs-walheim.de\\\/index.php\\\/2024\\\/03\\\/21\\\/schuelerparlament\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ggs-walheim.de\\\/index.php\\\/2024\\\/03\\\/21\\\/schuelerparlament\\\/\"},\"author\":{\"name\":\"Tanja Braun\",\"@id\":\"https:\\\/\\\/www.ggs-walheim.de\\\/#\\\/schema\\\/person\\\/1061c3ae66852b2c981184a8f306f601\"},\"headline\":\"Sch\u00fclerparlament\",\"datePublished\":\"2024-03-21T16:16:47+00:00\",\"dateModified\":\"2024-03-21T16:28:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ggs-walheim.de\\\/index.php\\\/2024\\\/03\\\/21\\\/schuelerparlament\\\/\"},\"wordCount\":38,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ggs-walheim.de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ggs-walheim.de\\\/index.php\\\/2024\\\/03\\\/21\\\/schuelerparlament\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ggs-walheim.de\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Schuelerparlament-1440x1080.jpg\",\"keywords\":[\"Kinder\",\"Regeln\",\"Sch\u00fcler\"],\"articleSection\":[\"Sch\u00fclerparlament\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ggs-walheim.de\\\/index.php\\\/2024\\\/03\\\/21\\\/schuelerparlament\\\/\",\"url\":\"https:\\\/\\\/www.ggs-walheim.de\\\/index.php\\\/2024\\\/03\\\/21\\\/schuelerparlament\\\/\",\"name\":\"Sch\u00fclerparlament - GGS Walheim\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ggs-walheim.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ggs-walheim.de\\\/index.php\\\/2024\\\/03\\\/21\\\/schuelerparlament\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ggs-walheim.de\\\/index.php\\\/2024\\\/03\\\/21\\\/schuelerparlament\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ggs-walheim.de\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Schuelerparlament-1440x1080.jpg\",\"datePublished\":\"2024-03-21T16:16:47+00:00\",\"dateModified\":\"2024-03-21T16:28:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ggs-walheim.de\\\/index.php\\\/2024\\\/03\\\/21\\\/schuelerparlament\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ggs-walheim.de\\\/index.php\\\/2024\\\/03\\\/21\\\/schuelerparlament\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.ggs-walheim.de\\\/index.php\\\/2024\\\/03\\\/21\\\/schuelerparlament\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ggs-walheim.de\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Schuelerparlament.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ggs-walheim.de\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Schuelerparlament.jpg\",\"width\":2048,\"height\":1536},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ggs-walheim.de\\\/index.php\\\/2024\\\/03\\\/21\\\/schuelerparlament\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.ggs-walheim.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sch\u00fclerparlament\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ggs-walheim.de\\\/#website\",\"url\":\"https:\\\/\\\/www.ggs-walheim.de\\\/\",\"name\":\"GGS Walheim\",\"description\":\"Zu Hause im Aachener S\u00fcden\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ggs-walheim.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ggs-walheim.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ggs-walheim.de\\\/#organization\",\"name\":\"St\u00e4dtische Gemeinschaftsgrundschule Walheim\",\"url\":\"https:\\\/\\\/www.ggs-walheim.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.ggs-walheim.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ggs-walheim.de\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/logo-ggs.png\",\"contentUrl\":\"https:\\\/\\\/www.ggs-walheim.de\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/logo-ggs.png\",\"width\":1363,\"height\":1363,\"caption\":\"St\u00e4dtische Gemeinschaftsgrundschule Walheim\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ggs-walheim.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ggs-walheim.de\\\/#\\\/schema\\\/person\\\/1061c3ae66852b2c981184a8f306f601\",\"name\":\"Tanja Braun\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ed9a9e7d8e42c39f57f1553c0be4549c2858987c08627d85c1abe11a99a75da1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ed9a9e7d8e42c39f57f1553c0be4549c2858987c08627d85c1abe11a99a75da1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ed9a9e7d8e42c39f57f1553c0be4549c2858987c08627d85c1abe11a99a75da1?s=96&d=mm&r=g\",\"caption\":\"Tanja Braun\"},\"url\":\"https:\\\/\\\/www.ggs-walheim.de\\\/index.php\\\/author\\\/tbraun\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sch\u00fclerparlament - GGS Walheim","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ggs-walheim.de\/index.php\/2024\/03\/21\/schuelerparlament\/","og_locale":"de_DE","og_type":"article","og_title":"Sch\u00fclerparlament - GGS Walheim","og_description":"Das Kinderparlament der Grundschule Walheim hat gearbeitet und getagt. Wichtige Schulregeln wurden besprochen und neu verabredet. Davon berichten die Klassensprecherinnen und Klassensprecher im Rahmen eines&hellip;","og_url":"https:\/\/www.ggs-walheim.de\/index.php\/2024\/03\/21\/schuelerparlament\/","og_site_name":"GGS Walheim","article_published_time":"2024-03-21T16:16:47+00:00","article_modified_time":"2024-03-21T16:28:23+00:00","og_image":[{"url":"https:\/\/www.ggs-walheim.de\/wp-content\/uploads\/2024\/03\/Schuelerparlament-1440x1080.jpg","type":"","width":"","height":""}],"author":"Tanja Braun","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Tanja Braun","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ggs-walheim.de\/index.php\/2024\/03\/21\/schuelerparlament\/#article","isPartOf":{"@id":"https:\/\/www.ggs-walheim.de\/index.php\/2024\/03\/21\/schuelerparlament\/"},"author":{"name":"Tanja Braun","@id":"https:\/\/www.ggs-walheim.de\/#\/schema\/person\/1061c3ae66852b2c981184a8f306f601"},"headline":"Sch\u00fclerparlament","datePublished":"2024-03-21T16:16:47+00:00","dateModified":"2024-03-21T16:28:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ggs-walheim.de\/index.php\/2024\/03\/21\/schuelerparlament\/"},"wordCount":38,"publisher":{"@id":"https:\/\/www.ggs-walheim.de\/#organization"},"image":{"@id":"https:\/\/www.ggs-walheim.de\/index.php\/2024\/03\/21\/schuelerparlament\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ggs-walheim.de\/wp-content\/uploads\/2024\/03\/Schuelerparlament-1440x1080.jpg","keywords":["Kinder","Regeln","Sch\u00fcler"],"articleSection":["Sch\u00fclerparlament"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.ggs-walheim.de\/index.php\/2024\/03\/21\/schuelerparlament\/","url":"https:\/\/www.ggs-walheim.de\/index.php\/2024\/03\/21\/schuelerparlament\/","name":"Sch\u00fclerparlament - GGS Walheim","isPartOf":{"@id":"https:\/\/www.ggs-walheim.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ggs-walheim.de\/index.php\/2024\/03\/21\/schuelerparlament\/#primaryimage"},"image":{"@id":"https:\/\/www.ggs-walheim.de\/index.php\/2024\/03\/21\/schuelerparlament\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ggs-walheim.de\/wp-content\/uploads\/2024\/03\/Schuelerparlament-1440x1080.jpg","datePublished":"2024-03-21T16:16:47+00:00","dateModified":"2024-03-21T16:28:23+00:00","breadcrumb":{"@id":"https:\/\/www.ggs-walheim.de\/index.php\/2024\/03\/21\/schuelerparlament\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ggs-walheim.de\/index.php\/2024\/03\/21\/schuelerparlament\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.ggs-walheim.de\/index.php\/2024\/03\/21\/schuelerparlament\/#primaryimage","url":"https:\/\/www.ggs-walheim.de\/wp-content\/uploads\/2024\/03\/Schuelerparlament.jpg","contentUrl":"https:\/\/www.ggs-walheim.de\/wp-content\/uploads\/2024\/03\/Schuelerparlament.jpg","width":2048,"height":1536},{"@type":"BreadcrumbList","@id":"https:\/\/www.ggs-walheim.de\/index.php\/2024\/03\/21\/schuelerparlament\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.ggs-walheim.de\/"},{"@type":"ListItem","position":2,"name":"Sch\u00fclerparlament"}]},{"@type":"WebSite","@id":"https:\/\/www.ggs-walheim.de\/#website","url":"https:\/\/www.ggs-walheim.de\/","name":"GGS Walheim","description":"Zu Hause im Aachener S\u00fcden","publisher":{"@id":"https:\/\/www.ggs-walheim.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ggs-walheim.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.ggs-walheim.de\/#organization","name":"St\u00e4dtische Gemeinschaftsgrundschule Walheim","url":"https:\/\/www.ggs-walheim.de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.ggs-walheim.de\/#\/schema\/logo\/image\/","url":"https:\/\/www.ggs-walheim.de\/wp-content\/uploads\/2020\/10\/logo-ggs.png","contentUrl":"https:\/\/www.ggs-walheim.de\/wp-content\/uploads\/2020\/10\/logo-ggs.png","width":1363,"height":1363,"caption":"St\u00e4dtische Gemeinschaftsgrundschule Walheim"},"image":{"@id":"https:\/\/www.ggs-walheim.de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.ggs-walheim.de\/#\/schema\/person\/1061c3ae66852b2c981184a8f306f601","name":"Tanja Braun","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/ed9a9e7d8e42c39f57f1553c0be4549c2858987c08627d85c1abe11a99a75da1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ed9a9e7d8e42c39f57f1553c0be4549c2858987c08627d85c1abe11a99a75da1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ed9a9e7d8e42c39f57f1553c0be4549c2858987c08627d85c1abe11a99a75da1?s=96&d=mm&r=g","caption":"Tanja Braun"},"url":"https:\/\/www.ggs-walheim.de\/index.php\/author\/tbraun\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ggs-walheim.de\/index.php\/wp-json\/wp\/v2\/posts\/2426","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ggs-walheim.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ggs-walheim.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ggs-walheim.de\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ggs-walheim.de\/index.php\/wp-json\/wp\/v2\/comments?post=2426"}],"version-history":[{"count":1,"href":"https:\/\/www.ggs-walheim.de\/index.php\/wp-json\/wp\/v2\/posts\/2426\/revisions"}],"predecessor-version":[{"id":2428,"href":"https:\/\/www.ggs-walheim.de\/index.php\/wp-json\/wp\/v2\/posts\/2426\/revisions\/2428"}],"wp:attachment":[{"href":"https:\/\/www.ggs-walheim.de\/index.php\/wp-json\/wp\/v2\/media?parent=2426"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ggs-walheim.de\/index.php\/wp-json\/wp\/v2\/categories?post=2426"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ggs-walheim.de\/index.php\/wp-json\/wp\/v2\/tags?post=2426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}