{"id":2422,"date":"2024-03-21T16:34:25","date_gmt":"2024-03-21T15:34:25","guid":{"rendered":"https:\/\/www.ggs-walheim.de\/?p=2422"},"modified":"2024-03-21T16:35:37","modified_gmt":"2024-03-21T15:35:37","slug":"schwimmsportfest-der-aachener-grundschulen-2024","status":"publish","type":"post","link":"https:\/\/www.ggs-walheim.de\/index.php\/2024\/03\/21\/schwimmsportfest-der-aachener-grundschulen-2024\/","title":{"rendered":"Schwimmsportfest der Aachener Grundschulen 2024"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1440\" height=\"1080\" src=\"https:\/\/www.ggs-walheim.de\/wp-content\/uploads\/2024\/03\/Schwimmen-1440x1080.jpg\" alt=\"\" class=\"wp-image-2423\" srcset=\"https:\/\/www.ggs-walheim.de\/wp-content\/uploads\/2024\/03\/Schwimmen-1440x1080.jpg 1440w, https:\/\/www.ggs-walheim.de\/wp-content\/uploads\/2024\/03\/Schwimmen-300x225.jpg 300w, https:\/\/www.ggs-walheim.de\/wp-content\/uploads\/2024\/03\/Schwimmen-1536x1152.jpg 1536w, https:\/\/www.ggs-walheim.de\/wp-content\/uploads\/2024\/03\/Schwimmen-2048x1536.jpg 2048w, https:\/\/www.ggs-walheim.de\/wp-content\/uploads\/2024\/03\/Schwimmen-800x600.jpg 800w\" sizes=\"auto, (max-width: 1440px) 100vw, 1440px\" \/><\/figure>\n\n\n\n<p>Am vergangenen Freitag (15. M\u00e4rz 2024) fand das Schwimmsportfest der Aachener Grundschulen statt. 12 Kinder aus den beiden 4. Klassen der Grundschule Walheim waren in 5 Disziplinen am Start und hatten mit 14 anderen Schulen zusammen eine Menge Spa\u00df. Unsere \u201eWalheimer Haie\u201c haben alles gegeben und nach einem aufregenden Vormittag in der Schwimmhalle Ost einen tollen 12. Platz gemacht. Jedes Kind hat eine Medaille und ein Pixi-Buch bekommen! Herzlichen Gl\u00fcckwunsch an alle Schwimmer und Schwimmerinnen! Ihr habt das super gemacht!<\/p>\n\n\n\n<p><strong>Hier einige Stimmen aus unserem Schwimm-Team:<\/strong><\/p>\n\n\n\n<p>\u201eEs war sehr cool. Es hat mir sehr viel Spa\u00df gemacht.\u201c&nbsp;<\/p>\n\n\n\n<p>\u201eWir mussten zuerst 7 Minuten lang hintereinander schwimmen. Unsere Bahnen wurden gez\u00e4hlt, es waren insgesamt 77 Bahnen, die wir mit 10 Kindern geschwommen sind.\u201c<\/p>\n\n\n\n<p>\u201eDas Ausdauerschwimmen fand ich am schwierigsten.\u201c<\/p>\n\n\n\n<p>\u201eIch bin stolz darauf, dass ich am Ende noch einen Sprint abgezogen habe.\u201c<\/p>\n\n\n\n<p>\u201eIch habe gedacht, dass ich es gut hinkriege und bin deshalb sehr schnell los geschwommen. Ich rate euch, tut das besser nicht.\u201c<\/p>\n\n\n\n<p>\u201eDanach mussten wir in einer Staffel auf Zeit sprinten, hin und zur\u00fcck. Das waren 50 Meter f\u00fcr jeden.\u201c<\/p>\n\n\n\n<p>\u201eNach einer kurzen Pause im kleinen Becken mussten wir tauchen. Dabei durfte jeder immer nur einen Ring holen. Nach 5 Minuten hatten wir 35 Ringe aus dem Wasser geholt.\u201c<\/p>\n\n\n\n<p>\u201eBeim Tauchen habe ich mich richtig gut gef\u00fchlt.\u201c<\/p>\n\n\n\n<p>\u201eAm besten fand ich aber das T-Shirt-Schwimmen.\u201c&nbsp;<\/p>\n\n\n\n<p>\u201eWir hatten die Aufgabe mit einem nassen T-Shirt eine Staffel zu schwimmen. Das war sehr cool. Wir durften uns gegenseitig helfen, das T-Shirt zu wechseln. Das hatten wir nat\u00fcrlich ge\u00fcbt und es hat super geklappt.\u201c<\/p>\n\n\n\n<p>\u201eIch war die letzte in der Kleiderstaffel und das war dann ein ziemlicher Druck: Was ist, wenn ich zu langsam bin? Aber ich habe es geschafft!\u201c<\/p>\n\n\n\n<p>\u201eZum Schluss hatten wir die Aufgabe wie ein Kellner mit Ringen auf einem Brett zu schwimmen. Es durfte kein Ring runterfallen. Das haben sogar alle Schulmannschaften geschafft.\u201c<\/p>\n\n\n\n<p>\u201eIch fand lustig, als ein paar Lehrer zum Abschluss des Schwimmsportfestes gegeneinander geschwommen sind.\u201c<\/p>\n\n\n\n<p>\u201eIch habe mich gewundert, wie schnell Frau M\u00f6ller und Herr Sch\u00f6nborn schwimmen k\u00f6nnen.\u201c<\/p>\n\n\n\n<p>\u201eIch fand gut, dass bei der Siegerehrung alle Kinder eine Medaille und ein Pixi-Buch bekommen haben.\u201c<\/p>\n\n\n\n<p>\u201eIch war sehr zufrieden mit der Platzierung.\u201c \u201eEs war sch\u00f6n, weil wir zusammengearbeitet haben.\u201c<\/p>\n\n\n\n<p>&nbsp;\u201eEs war auch cool, dass ich Freunde aus anderen Schulen getroffen habe.\u201c<\/p>\n\n\n\n<p>\u201eIch will noch einen gro\u00dfen Dank an mein Team ausrichten, dass sie mich so gut angefeuert haben.\u201c<\/p>\n\n\n\n<p>Herzlichen Dank an alle Eltern, die Fahrgemeinschaften gebildet haben und uns vor Ort angefeuert haben.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Am vergangenen Freitag (15. M\u00e4rz 2024) fand das Schwimmsportfest der Aachener Grundschulen statt. 12 Kinder aus den beiden 4. Klassen der Grundschule Walheim waren in&hellip;<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":"","footnotes":""},"categories":[30],"tags":[283,2],"class_list":["post-2422","post","type-post","status-publish","format-standard","hentry","category-schwimmen","tag-schwimmen","tag-sport"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Schwimmsportfest der Aachener Grundschulen 2024 - GGS Walheim<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ggs-walheim.de\/index.php\/2024\/03\/21\/schwimmsportfest-der-aachener-grundschulen-2024\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Schwimmsportfest der Aachener Grundschulen 2024 - GGS Walheim\" \/>\n<meta property=\"og:description\" content=\"Am vergangenen Freitag (15. M\u00e4rz 2024) fand das Schwimmsportfest der Aachener Grundschulen statt. 12 Kinder aus den beiden 4. Klassen der Grundschule Walheim waren in&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ggs-walheim.de\/index.php\/2024\/03\/21\/schwimmsportfest-der-aachener-grundschulen-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"GGS Walheim\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-21T15:34:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-21T15:35:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ggs-walheim.de\/wp-content\/uploads\/2024\/03\/Schwimmen-1440x1080.jpg\" \/>\n<meta name=\"author\" content=\"Tanja Braun\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tanja Braun\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ggs-walheim.de\\\/index.php\\\/2024\\\/03\\\/21\\\/schwimmsportfest-der-aachener-grundschulen-2024\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ggs-walheim.de\\\/index.php\\\/2024\\\/03\\\/21\\\/schwimmsportfest-der-aachener-grundschulen-2024\\\/\"},\"author\":{\"name\":\"Tanja Braun\",\"@id\":\"https:\\\/\\\/www.ggs-walheim.de\\\/#\\\/schema\\\/person\\\/1061c3ae66852b2c981184a8f306f601\"},\"headline\":\"Schwimmsportfest der Aachener Grundschulen 2024\",\"datePublished\":\"2024-03-21T15:34:25+00:00\",\"dateModified\":\"2024-03-21T15:35:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ggs-walheim.de\\\/index.php\\\/2024\\\/03\\\/21\\\/schwimmsportfest-der-aachener-grundschulen-2024\\\/\"},\"wordCount\":420,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ggs-walheim.de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ggs-walheim.de\\\/index.php\\\/2024\\\/03\\\/21\\\/schwimmsportfest-der-aachener-grundschulen-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ggs-walheim.de\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Schwimmen-1440x1080.jpg\",\"keywords\":[\"Schwimmen\",\"sport\"],\"articleSection\":[\"Schwimmen\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ggs-walheim.de\\\/index.php\\\/2024\\\/03\\\/21\\\/schwimmsportfest-der-aachener-grundschulen-2024\\\/\",\"url\":\"https:\\\/\\\/www.ggs-walheim.de\\\/index.php\\\/2024\\\/03\\\/21\\\/schwimmsportfest-der-aachener-grundschulen-2024\\\/\",\"name\":\"Schwimmsportfest der Aachener Grundschulen 2024 - GGS Walheim\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ggs-walheim.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ggs-walheim.de\\\/index.php\\\/2024\\\/03\\\/21\\\/schwimmsportfest-der-aachener-grundschulen-2024\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ggs-walheim.de\\\/index.php\\\/2024\\\/03\\\/21\\\/schwimmsportfest-der-aachener-grundschulen-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ggs-walheim.de\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Schwimmen-1440x1080.jpg\",\"datePublished\":\"2024-03-21T15:34:25+00:00\",\"dateModified\":\"2024-03-21T15:35:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ggs-walheim.de\\\/index.php\\\/2024\\\/03\\\/21\\\/schwimmsportfest-der-aachener-grundschulen-2024\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ggs-walheim.de\\\/index.php\\\/2024\\\/03\\\/21\\\/schwimmsportfest-der-aachener-grundschulen-2024\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.ggs-walheim.de\\\/index.php\\\/2024\\\/03\\\/21\\\/schwimmsportfest-der-aachener-grundschulen-2024\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ggs-walheim.de\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Schwimmen-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ggs-walheim.de\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Schwimmen-scaled.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ggs-walheim.de\\\/index.php\\\/2024\\\/03\\\/21\\\/schwimmsportfest-der-aachener-grundschulen-2024\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.ggs-walheim.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Schwimmsportfest der Aachener Grundschulen 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ggs-walheim.de\\\/#website\",\"url\":\"https:\\\/\\\/www.ggs-walheim.de\\\/\",\"name\":\"GGS Walheim\",\"description\":\"Zu Hause im Aachener S\u00fcden\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ggs-walheim.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ggs-walheim.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ggs-walheim.de\\\/#organization\",\"name\":\"St\u00e4dtische Gemeinschaftsgrundschule Walheim\",\"url\":\"https:\\\/\\\/www.ggs-walheim.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.ggs-walheim.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ggs-walheim.de\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/logo-ggs.png\",\"contentUrl\":\"https:\\\/\\\/www.ggs-walheim.de\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/logo-ggs.png\",\"width\":1363,\"height\":1363,\"caption\":\"St\u00e4dtische Gemeinschaftsgrundschule Walheim\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ggs-walheim.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ggs-walheim.de\\\/#\\\/schema\\\/person\\\/1061c3ae66852b2c981184a8f306f601\",\"name\":\"Tanja Braun\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ed9a9e7d8e42c39f57f1553c0be4549c2858987c08627d85c1abe11a99a75da1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ed9a9e7d8e42c39f57f1553c0be4549c2858987c08627d85c1abe11a99a75da1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ed9a9e7d8e42c39f57f1553c0be4549c2858987c08627d85c1abe11a99a75da1?s=96&d=mm&r=g\",\"caption\":\"Tanja Braun\"},\"url\":\"https:\\\/\\\/www.ggs-walheim.de\\\/index.php\\\/author\\\/tbraun\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Schwimmsportfest der Aachener Grundschulen 2024 - GGS Walheim","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ggs-walheim.de\/index.php\/2024\/03\/21\/schwimmsportfest-der-aachener-grundschulen-2024\/","og_locale":"de_DE","og_type":"article","og_title":"Schwimmsportfest der Aachener Grundschulen 2024 - GGS Walheim","og_description":"Am vergangenen Freitag (15. M\u00e4rz 2024) fand das Schwimmsportfest der Aachener Grundschulen statt. 12 Kinder aus den beiden 4. Klassen der Grundschule Walheim waren in&hellip;","og_url":"https:\/\/www.ggs-walheim.de\/index.php\/2024\/03\/21\/schwimmsportfest-der-aachener-grundschulen-2024\/","og_site_name":"GGS Walheim","article_published_time":"2024-03-21T15:34:25+00:00","article_modified_time":"2024-03-21T15:35:37+00:00","og_image":[{"url":"https:\/\/www.ggs-walheim.de\/wp-content\/uploads\/2024\/03\/Schwimmen-1440x1080.jpg","type":"","width":"","height":""}],"author":"Tanja Braun","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Tanja Braun","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ggs-walheim.de\/index.php\/2024\/03\/21\/schwimmsportfest-der-aachener-grundschulen-2024\/#article","isPartOf":{"@id":"https:\/\/www.ggs-walheim.de\/index.php\/2024\/03\/21\/schwimmsportfest-der-aachener-grundschulen-2024\/"},"author":{"name":"Tanja Braun","@id":"https:\/\/www.ggs-walheim.de\/#\/schema\/person\/1061c3ae66852b2c981184a8f306f601"},"headline":"Schwimmsportfest der Aachener Grundschulen 2024","datePublished":"2024-03-21T15:34:25+00:00","dateModified":"2024-03-21T15:35:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ggs-walheim.de\/index.php\/2024\/03\/21\/schwimmsportfest-der-aachener-grundschulen-2024\/"},"wordCount":420,"publisher":{"@id":"https:\/\/www.ggs-walheim.de\/#organization"},"image":{"@id":"https:\/\/www.ggs-walheim.de\/index.php\/2024\/03\/21\/schwimmsportfest-der-aachener-grundschulen-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ggs-walheim.de\/wp-content\/uploads\/2024\/03\/Schwimmen-1440x1080.jpg","keywords":["Schwimmen","sport"],"articleSection":["Schwimmen"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.ggs-walheim.de\/index.php\/2024\/03\/21\/schwimmsportfest-der-aachener-grundschulen-2024\/","url":"https:\/\/www.ggs-walheim.de\/index.php\/2024\/03\/21\/schwimmsportfest-der-aachener-grundschulen-2024\/","name":"Schwimmsportfest der Aachener Grundschulen 2024 - GGS Walheim","isPartOf":{"@id":"https:\/\/www.ggs-walheim.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ggs-walheim.de\/index.php\/2024\/03\/21\/schwimmsportfest-der-aachener-grundschulen-2024\/#primaryimage"},"image":{"@id":"https:\/\/www.ggs-walheim.de\/index.php\/2024\/03\/21\/schwimmsportfest-der-aachener-grundschulen-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ggs-walheim.de\/wp-content\/uploads\/2024\/03\/Schwimmen-1440x1080.jpg","datePublished":"2024-03-21T15:34:25+00:00","dateModified":"2024-03-21T15:35:37+00:00","breadcrumb":{"@id":"https:\/\/www.ggs-walheim.de\/index.php\/2024\/03\/21\/schwimmsportfest-der-aachener-grundschulen-2024\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ggs-walheim.de\/index.php\/2024\/03\/21\/schwimmsportfest-der-aachener-grundschulen-2024\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.ggs-walheim.de\/index.php\/2024\/03\/21\/schwimmsportfest-der-aachener-grundschulen-2024\/#primaryimage","url":"https:\/\/www.ggs-walheim.de\/wp-content\/uploads\/2024\/03\/Schwimmen-scaled.jpg","contentUrl":"https:\/\/www.ggs-walheim.de\/wp-content\/uploads\/2024\/03\/Schwimmen-scaled.jpg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/www.ggs-walheim.de\/index.php\/2024\/03\/21\/schwimmsportfest-der-aachener-grundschulen-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.ggs-walheim.de\/"},{"@type":"ListItem","position":2,"name":"Schwimmsportfest der Aachener Grundschulen 2024"}]},{"@type":"WebSite","@id":"https:\/\/www.ggs-walheim.de\/#website","url":"https:\/\/www.ggs-walheim.de\/","name":"GGS Walheim","description":"Zu Hause im Aachener S\u00fcden","publisher":{"@id":"https:\/\/www.ggs-walheim.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ggs-walheim.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.ggs-walheim.de\/#organization","name":"St\u00e4dtische Gemeinschaftsgrundschule Walheim","url":"https:\/\/www.ggs-walheim.de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.ggs-walheim.de\/#\/schema\/logo\/image\/","url":"https:\/\/www.ggs-walheim.de\/wp-content\/uploads\/2020\/10\/logo-ggs.png","contentUrl":"https:\/\/www.ggs-walheim.de\/wp-content\/uploads\/2020\/10\/logo-ggs.png","width":1363,"height":1363,"caption":"St\u00e4dtische Gemeinschaftsgrundschule Walheim"},"image":{"@id":"https:\/\/www.ggs-walheim.de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.ggs-walheim.de\/#\/schema\/person\/1061c3ae66852b2c981184a8f306f601","name":"Tanja Braun","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/ed9a9e7d8e42c39f57f1553c0be4549c2858987c08627d85c1abe11a99a75da1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ed9a9e7d8e42c39f57f1553c0be4549c2858987c08627d85c1abe11a99a75da1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ed9a9e7d8e42c39f57f1553c0be4549c2858987c08627d85c1abe11a99a75da1?s=96&d=mm&r=g","caption":"Tanja Braun"},"url":"https:\/\/www.ggs-walheim.de\/index.php\/author\/tbraun\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ggs-walheim.de\/index.php\/wp-json\/wp\/v2\/posts\/2422","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ggs-walheim.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ggs-walheim.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ggs-walheim.de\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ggs-walheim.de\/index.php\/wp-json\/wp\/v2\/comments?post=2422"}],"version-history":[{"count":1,"href":"https:\/\/www.ggs-walheim.de\/index.php\/wp-json\/wp\/v2\/posts\/2422\/revisions"}],"predecessor-version":[{"id":2424,"href":"https:\/\/www.ggs-walheim.de\/index.php\/wp-json\/wp\/v2\/posts\/2422\/revisions\/2424"}],"wp:attachment":[{"href":"https:\/\/www.ggs-walheim.de\/index.php\/wp-json\/wp\/v2\/media?parent=2422"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ggs-walheim.de\/index.php\/wp-json\/wp\/v2\/categories?post=2422"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ggs-walheim.de\/index.php\/wp-json\/wp\/v2\/tags?post=2422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}