{"id":1577,"date":"2021-05-27T10:00:50","date_gmt":"2021-05-27T08:00:50","guid":{"rendered":"https:\/\/www.ggs-walheim.de\/?p=1577"},"modified":"2021-06-25T18:42:20","modified_gmt":"2021-06-25T16:42:20","slug":"die-blumenbeete-in-voller-pracht","status":"publish","type":"post","link":"https:\/\/www.ggs-walheim.de\/index.php\/2021\/05\/27\/die-blumenbeete-in-voller-pracht\/","title":{"rendered":"Die Blumenbeete in voller Pracht!"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Auch wenn das Wetter momentan ziemlich durchwachsen ist, hat sich seit einigen Wochen etwas in unserem Schulgarten getan: Unsere Blumenbeete bl\u00fchen in voller Pracht!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Kinder der zweiten Schuljahre hatten im November die Zwiebeln gepflanzt (wir hatten <a href=\"https:\/\/www.ggs-walheim.de\/index.php\/2020\/11\/17\/neue-bepflanzung-der-beete\/\">hier<\/a> dar\u00fcber berichtet) und nun kann man endlich das tolle Ergebnis sehen. Besonders bei Sonnenschein sind die Fr\u00fchbl\u00fcher eine echte Augenweide, wenn man durch den Schulgarten geht.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hier ein kurzes Video von den Beeten:<\/p>\n\n\n\n<figure class=\"wp-block-video\"><video height=\"1080\" style=\"aspect-ratio: 1920 \/ 1080;\" width=\"1920\" autoplay controls loop muted src=\"https:\/\/www.ggs-walheim.de\/wp-content\/uploads\/2021\/05\/Blumenbeete-GGS-Walheim.mp4\"><\/video><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Auch wenn das Wetter momentan ziemlich durchwachsen ist, hat sich seit einigen Wochen etwas in unserem Schulgarten getan: Unsere Blumenbeete bl\u00fchen in voller Pracht! Die&hellip;<\/p>\n","protected":false},"author":1,"featured_media":1598,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":"","footnotes":""},"categories":[121],"tags":[86,119,120,184,183,90,84,85],"class_list":["post-1577","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-schulgarten","tag-aachen","tag-blumenbeete","tag-bulbs4kids","tag-fruehblueher","tag-fruehling","tag-ggs","tag-grundschule","tag-walheim"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Die Blumenbeete in voller Pracht! - GGS Walheim<\/title>\n<meta name=\"description\" content=\"Auch wenn das Wetter momentan ziemlich durchwachsen ist, hat sich seit einigen Wochen etwas in unserem Schulgarten getan: Unsere Blumenbeete bl\u00fchen in voller Pracht!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ggs-walheim.de\/index.php\/2021\/05\/27\/die-blumenbeete-in-voller-pracht\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die Blumenbeete in voller Pracht! - GGS Walheim\" \/>\n<meta property=\"og:description\" content=\"Auch wenn das Wetter momentan ziemlich durchwachsen ist, hat sich seit einigen Wochen etwas in unserem Schulgarten getan: Unsere Blumenbeete bl\u00fchen in voller Pracht!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ggs-walheim.de\/index.php\/2021\/05\/27\/die-blumenbeete-in-voller-pracht\/\" \/>\n<meta property=\"og:site_name\" content=\"GGS Walheim\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-27T08:00:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-25T16:42:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ggs-walheim.de\/wp-content\/uploads\/2021\/05\/Blumenbeet.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"GGS Walheim\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"GGS Walheim\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ggs-walheim.de\\\/index.php\\\/2021\\\/05\\\/27\\\/die-blumenbeete-in-voller-pracht\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ggs-walheim.de\\\/index.php\\\/2021\\\/05\\\/27\\\/die-blumenbeete-in-voller-pracht\\\/\"},\"author\":{\"name\":\"GGS Walheim\",\"@id\":\"https:\\\/\\\/www.ggs-walheim.de\\\/#\\\/schema\\\/person\\\/dc498b4c02ff41b1686e53870c3f1d3a\"},\"headline\":\"Die Blumenbeete in voller Pracht!\",\"datePublished\":\"2021-05-27T08:00:50+00:00\",\"dateModified\":\"2021-06-25T16:42:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ggs-walheim.de\\\/index.php\\\/2021\\\/05\\\/27\\\/die-blumenbeete-in-voller-pracht\\\/\"},\"wordCount\":80,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ggs-walheim.de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ggs-walheim.de\\\/index.php\\\/2021\\\/05\\\/27\\\/die-blumenbeete-in-voller-pracht\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ggs-walheim.de\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Blumenbeet.jpg\",\"keywords\":[\"Aachen\",\"Blumenbeete\",\"Bulbs4Kids\",\"Fr\u00fchbl\u00fcher\",\"Fr\u00fchling\",\"GGS\",\"Grundschule\",\"Walheim\"],\"articleSection\":[\"Schulgarten\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ggs-walheim.de\\\/index.php\\\/2021\\\/05\\\/27\\\/die-blumenbeete-in-voller-pracht\\\/\",\"url\":\"https:\\\/\\\/www.ggs-walheim.de\\\/index.php\\\/2021\\\/05\\\/27\\\/die-blumenbeete-in-voller-pracht\\\/\",\"name\":\"Die Blumenbeete in voller Pracht! - GGS Walheim\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ggs-walheim.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ggs-walheim.de\\\/index.php\\\/2021\\\/05\\\/27\\\/die-blumenbeete-in-voller-pracht\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ggs-walheim.de\\\/index.php\\\/2021\\\/05\\\/27\\\/die-blumenbeete-in-voller-pracht\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ggs-walheim.de\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Blumenbeet.jpg\",\"datePublished\":\"2021-05-27T08:00:50+00:00\",\"dateModified\":\"2021-06-25T16:42:20+00:00\",\"description\":\"Auch wenn das Wetter momentan ziemlich durchwachsen ist, hat sich seit einigen Wochen etwas in unserem Schulgarten getan: Unsere Blumenbeete bl\u00fchen in voller Pracht!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ggs-walheim.de\\\/index.php\\\/2021\\\/05\\\/27\\\/die-blumenbeete-in-voller-pracht\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ggs-walheim.de\\\/index.php\\\/2021\\\/05\\\/27\\\/die-blumenbeete-in-voller-pracht\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.ggs-walheim.de\\\/index.php\\\/2021\\\/05\\\/27\\\/die-blumenbeete-in-voller-pracht\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ggs-walheim.de\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Blumenbeet.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ggs-walheim.de\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Blumenbeet.jpg\",\"width\":1024,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ggs-walheim.de\\\/index.php\\\/2021\\\/05\\\/27\\\/die-blumenbeete-in-voller-pracht\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.ggs-walheim.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die Blumenbeete in voller Pracht!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ggs-walheim.de\\\/#website\",\"url\":\"https:\\\/\\\/www.ggs-walheim.de\\\/\",\"name\":\"GGS Walheim\",\"description\":\"Zu Hause im Aachener S\u00fcden\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ggs-walheim.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ggs-walheim.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ggs-walheim.de\\\/#organization\",\"name\":\"St\u00e4dtische Gemeinschaftsgrundschule Walheim\",\"url\":\"https:\\\/\\\/www.ggs-walheim.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.ggs-walheim.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ggs-walheim.de\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/logo-ggs.png\",\"contentUrl\":\"https:\\\/\\\/www.ggs-walheim.de\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/logo-ggs.png\",\"width\":1363,\"height\":1363,\"caption\":\"St\u00e4dtische Gemeinschaftsgrundschule Walheim\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ggs-walheim.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ggs-walheim.de\\\/#\\\/schema\\\/person\\\/dc498b4c02ff41b1686e53870c3f1d3a\",\"name\":\"GGS Walheim\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23f48a97eefdf604c89fbb81af5e467a1fc46f923bb9a338ac540f530aeb7dc4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23f48a97eefdf604c89fbb81af5e467a1fc46f923bb9a338ac540f530aeb7dc4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23f48a97eefdf604c89fbb81af5e467a1fc46f923bb9a338ac540f530aeb7dc4?s=96&d=mm&r=g\",\"caption\":\"GGS Walheim\"},\"url\":\"https:\\\/\\\/www.ggs-walheim.de\\\/index.php\\\/author\\\/ggs-walheim\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die Blumenbeete in voller Pracht! - GGS Walheim","description":"Auch wenn das Wetter momentan ziemlich durchwachsen ist, hat sich seit einigen Wochen etwas in unserem Schulgarten getan: Unsere Blumenbeete bl\u00fchen in voller Pracht!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ggs-walheim.de\/index.php\/2021\/05\/27\/die-blumenbeete-in-voller-pracht\/","og_locale":"de_DE","og_type":"article","og_title":"Die Blumenbeete in voller Pracht! - GGS Walheim","og_description":"Auch wenn das Wetter momentan ziemlich durchwachsen ist, hat sich seit einigen Wochen etwas in unserem Schulgarten getan: Unsere Blumenbeete bl\u00fchen in voller Pracht!","og_url":"https:\/\/www.ggs-walheim.de\/index.php\/2021\/05\/27\/die-blumenbeete-in-voller-pracht\/","og_site_name":"GGS Walheim","article_published_time":"2021-05-27T08:00:50+00:00","article_modified_time":"2021-06-25T16:42:20+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/www.ggs-walheim.de\/wp-content\/uploads\/2021\/05\/Blumenbeet.jpg","type":"image\/jpeg"}],"author":"GGS Walheim","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"GGS Walheim","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ggs-walheim.de\/index.php\/2021\/05\/27\/die-blumenbeete-in-voller-pracht\/#article","isPartOf":{"@id":"https:\/\/www.ggs-walheim.de\/index.php\/2021\/05\/27\/die-blumenbeete-in-voller-pracht\/"},"author":{"name":"GGS Walheim","@id":"https:\/\/www.ggs-walheim.de\/#\/schema\/person\/dc498b4c02ff41b1686e53870c3f1d3a"},"headline":"Die Blumenbeete in voller Pracht!","datePublished":"2021-05-27T08:00:50+00:00","dateModified":"2021-06-25T16:42:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ggs-walheim.de\/index.php\/2021\/05\/27\/die-blumenbeete-in-voller-pracht\/"},"wordCount":80,"publisher":{"@id":"https:\/\/www.ggs-walheim.de\/#organization"},"image":{"@id":"https:\/\/www.ggs-walheim.de\/index.php\/2021\/05\/27\/die-blumenbeete-in-voller-pracht\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ggs-walheim.de\/wp-content\/uploads\/2021\/05\/Blumenbeet.jpg","keywords":["Aachen","Blumenbeete","Bulbs4Kids","Fr\u00fchbl\u00fcher","Fr\u00fchling","GGS","Grundschule","Walheim"],"articleSection":["Schulgarten"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.ggs-walheim.de\/index.php\/2021\/05\/27\/die-blumenbeete-in-voller-pracht\/","url":"https:\/\/www.ggs-walheim.de\/index.php\/2021\/05\/27\/die-blumenbeete-in-voller-pracht\/","name":"Die Blumenbeete in voller Pracht! - GGS Walheim","isPartOf":{"@id":"https:\/\/www.ggs-walheim.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ggs-walheim.de\/index.php\/2021\/05\/27\/die-blumenbeete-in-voller-pracht\/#primaryimage"},"image":{"@id":"https:\/\/www.ggs-walheim.de\/index.php\/2021\/05\/27\/die-blumenbeete-in-voller-pracht\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ggs-walheim.de\/wp-content\/uploads\/2021\/05\/Blumenbeet.jpg","datePublished":"2021-05-27T08:00:50+00:00","dateModified":"2021-06-25T16:42:20+00:00","description":"Auch wenn das Wetter momentan ziemlich durchwachsen ist, hat sich seit einigen Wochen etwas in unserem Schulgarten getan: Unsere Blumenbeete bl\u00fchen in voller Pracht!","breadcrumb":{"@id":"https:\/\/www.ggs-walheim.de\/index.php\/2021\/05\/27\/die-blumenbeete-in-voller-pracht\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ggs-walheim.de\/index.php\/2021\/05\/27\/die-blumenbeete-in-voller-pracht\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.ggs-walheim.de\/index.php\/2021\/05\/27\/die-blumenbeete-in-voller-pracht\/#primaryimage","url":"https:\/\/www.ggs-walheim.de\/wp-content\/uploads\/2021\/05\/Blumenbeet.jpg","contentUrl":"https:\/\/www.ggs-walheim.de\/wp-content\/uploads\/2021\/05\/Blumenbeet.jpg","width":1024,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/www.ggs-walheim.de\/index.php\/2021\/05\/27\/die-blumenbeete-in-voller-pracht\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.ggs-walheim.de\/"},{"@type":"ListItem","position":2,"name":"Die Blumenbeete in voller Pracht!"}]},{"@type":"WebSite","@id":"https:\/\/www.ggs-walheim.de\/#website","url":"https:\/\/www.ggs-walheim.de\/","name":"GGS Walheim","description":"Zu Hause im Aachener S\u00fcden","publisher":{"@id":"https:\/\/www.ggs-walheim.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ggs-walheim.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.ggs-walheim.de\/#organization","name":"St\u00e4dtische Gemeinschaftsgrundschule Walheim","url":"https:\/\/www.ggs-walheim.de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.ggs-walheim.de\/#\/schema\/logo\/image\/","url":"https:\/\/www.ggs-walheim.de\/wp-content\/uploads\/2020\/10\/logo-ggs.png","contentUrl":"https:\/\/www.ggs-walheim.de\/wp-content\/uploads\/2020\/10\/logo-ggs.png","width":1363,"height":1363,"caption":"St\u00e4dtische Gemeinschaftsgrundschule Walheim"},"image":{"@id":"https:\/\/www.ggs-walheim.de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.ggs-walheim.de\/#\/schema\/person\/dc498b4c02ff41b1686e53870c3f1d3a","name":"GGS Walheim","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/23f48a97eefdf604c89fbb81af5e467a1fc46f923bb9a338ac540f530aeb7dc4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/23f48a97eefdf604c89fbb81af5e467a1fc46f923bb9a338ac540f530aeb7dc4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/23f48a97eefdf604c89fbb81af5e467a1fc46f923bb9a338ac540f530aeb7dc4?s=96&d=mm&r=g","caption":"GGS Walheim"},"url":"https:\/\/www.ggs-walheim.de\/index.php\/author\/ggs-walheim\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ggs-walheim.de\/index.php\/wp-json\/wp\/v2\/posts\/1577","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ggs-walheim.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ggs-walheim.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ggs-walheim.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ggs-walheim.de\/index.php\/wp-json\/wp\/v2\/comments?post=1577"}],"version-history":[{"count":7,"href":"https:\/\/www.ggs-walheim.de\/index.php\/wp-json\/wp\/v2\/posts\/1577\/revisions"}],"predecessor-version":[{"id":1664,"href":"https:\/\/www.ggs-walheim.de\/index.php\/wp-json\/wp\/v2\/posts\/1577\/revisions\/1664"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ggs-walheim.de\/index.php\/wp-json\/wp\/v2\/media\/1598"}],"wp:attachment":[{"href":"https:\/\/www.ggs-walheim.de\/index.php\/wp-json\/wp\/v2\/media?parent=1577"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ggs-walheim.de\/index.php\/wp-json\/wp\/v2\/categories?post=1577"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ggs-walheim.de\/index.php\/wp-json\/wp\/v2\/tags?post=1577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}